{"id":1836,"date":"2022-03-08T12:30:25","date_gmt":"2022-03-08T12:30:25","guid":{"rendered":"https:\/\/abatigroup.it\/?p=1836"},"modified":"2022-06-10T12:13:36","modified_gmt":"2022-06-10T12:13:36","slug":"il-filato-che-non-ti-aspetti-rame-un-alleato-del-benessere","status":"publish","type":"post","link":"https:\/\/abatigroup.it\/en\/2022\/03\/08\/il-filato-che-non-ti-aspetti-rame-un-alleato-del-benessere\/","title":{"rendered":"Il Filato che non Ti aspetti: Rame, un alleato del benessere"},"content":{"rendered":"\n<p>Un approfondimento storico, alla riscoperta di usi e costumi dell&#8217;antichit\u00e0, per tornare al presente e scoprire come, materie prime che dalla notte dei tempi forgiano la storia dell&#8217;uomo, sono ancora oggi le principali alleate per duttilit\u00e0 e benessere. Nella fattispecie, oggi, parliamo del Rame, presentato sottoforma di fibra super sottile e lavorato con supporti tessili per dare vita ad una nuova forma di performance e protezione.<\/p>\n\n\n\n<p>Entriamo nel mondo dei filati performanti, tecnici e unici firmati Resistex, con Resistex Copper, che possiede 5 propriet\u00e0 fondamentali:<\/p>\n\n\n\n<ul><li>Propriet\u00e0 Antistatica (versione no smalto): disperde le cariche elettriche accumulate dall\u2019ambiente;<\/li><li>Propriet\u00e0 Metaboliche: assimilato attraverso la pelle aiuta il corpo a crescere e mantenersi in salute;<\/li><li>Propriet\u00e0 Antiossidanti: combatte i radicali liberi, causa dell\u2019invecchiamento cellulare;<\/li><li>Propriet\u00e0 Traspiranti: accelera il processo di evaporazione del sudore;<\/li><li>Propriet\u00e0 Termoregolanti: rallenta la formazione di umidit\u00e0 mantenendo la temperatura costante.<\/li><\/ul>\n\n\n\n<p>Tecnofilati, con Resistex\u00ae Copper, ha trovato il modo di veicolare i principali benefici presenti nel rame a favore del corpo umano, consentendo al filato di agire su tre livelli essenziali:<\/p>\n\n\n\n<ul><li>livello biochimico:attraverso l\u2019assorbimento di rame tramite la pelle, per via osmotica;<\/li><li>livello elettromagnetico: quale circuito di risonanza;<\/li><li>livello bioelettrico: regolando le microcorrenti dell\u2019organismo.<\/li><\/ul>\n\n\n\n<p>Questa importante scoperta si basa sulla Cupro Terapia, che dimostra come il rame possa essere assimilato non solamente con i cibi e l\u2019acqua potabile, ma anche attraverso la pelle, posta a contatto costante con i tessuti contenenti filati in Resistex\u00ae Copper. La Cupro Terapia \u00e8 l\u2019utilizzo a scopo terapeutico del rame o dei suoi sali. I braccialetti di rame erano utilizzati gi\u00e0 6000 anni prima di Cristo, e tra chi li consigliava per migliorare lo stato di salute rintracciamo Aristotele, Galeno, Ippocrate e Avicenna.&nbsp;Un\u2019indagine compiuta su 300 persone sofferenti di artrite e alle quali sono stati fatti indossare braccialetti di rame ha evidenziato come un \u201csignificativo numero\u201d di essi abbia dichiarato di aver avuto benefici dal braccialetto.&nbsp;Inoltre i controlli hanno evidenziato come i braccialetti avessero perduto 50 mg in un periodo di 50 giorni.<\/p>\n\n\n\n<p>La gamma di \ufb01lati Resistex\u00ae Copper \u00e8 impiegata per la sua natura di conducibilit\u00e0 elettrica, per l\u2019ottima termo-conduzione, per l\u2019azione antibatterica e per le propriet\u00e0 bene\ufb01che per il corpo umano.&nbsp;Grazie alle sue eccezionali caratteristiche, Resistex\u00ae Copper \u00e8 attualmente utilizzato per la produzione di tessuti tecnici che richiedono particolari performance, di conducibilit\u00e0 elettrica, termica e antibatterica.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa importante scoperta si basa sulla Cupro Terapia, che dimostra come il rame possa essere assimilato non solamente con i cibi e l\u2019acqua potabile, ma anche attraverso la pelle, posta a contatto costante con i tessuti contenenti filati in Resistex\u00ae Copper. <\/p>\n","protected":false},"author":3,"featured_media":1837,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[8],"tags":[],"_links":{"self":[{"href":"https:\/\/abatigroup.it\/en\/wp-json\/wp\/v2\/posts\/1836"}],"collection":[{"href":"https:\/\/abatigroup.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abatigroup.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abatigroup.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/abatigroup.it\/en\/wp-json\/wp\/v2\/comments?post=1836"}],"version-history":[{"count":1,"href":"https:\/\/abatigroup.it\/en\/wp-json\/wp\/v2\/posts\/1836\/revisions"}],"predecessor-version":[{"id":1839,"href":"https:\/\/abatigroup.it\/en\/wp-json\/wp\/v2\/posts\/1836\/revisions\/1839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abatigroup.it\/en\/wp-json\/wp\/v2\/media\/1837"}],"wp:attachment":[{"href":"https:\/\/abatigroup.it\/en\/wp-json\/wp\/v2\/media?parent=1836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abatigroup.it\/en\/wp-json\/wp\/v2\/categories?post=1836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abatigroup.it\/en\/wp-json\/wp\/v2\/tags?post=1836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}